{"id":97,"date":"2016-10-17T12:43:00","date_gmt":"2016-10-17T10:43:00","guid":{"rendered":"http:\/\/universita.chiesadigenova.it\/mercoledi-26-ottobre-2016-santa-messa-inizio-anno\/"},"modified":"2016-10-17T12:43:00","modified_gmt":"2016-10-17T10:43:00","slug":"mercoledi-26-ottobre-2016-santa-messa-inizio-anno","status":"publish","type":"post","link":"https:\/\/www.chiesadigenova.it\/universita\/mercoledi-26-ottobre-2016-santa-messa-inizio-anno\/","title":{"rendered":"MERCOLEDI&#8217; 26 OTTOBRE 2016 SANTA MESSA INIZIO ANNO"},"content":{"rendered":"<div>\u00a0Arcidiocesi di Genova &#8211; Ufficio per la Pastorale universitaria<\/div>\n<div>Santa Messa inizio anno accademico; Chiesa N.S. della Consolazione e S. Vincenzo Martire ( Via XX Settembre) alle ore 18<\/div>\n<div>Presieduta da S.E. Mons. Nicol\u00f2 Anselmi &#8211; Vescovo Ausiliare di Genova<\/div>\n<div>\u00a0<\/div>\n<div>Sono invitati studenti, docenti, personale tecnico ed amministrativo dell&#8217;ateneo genovese.<\/div>\n<div>Saranno presenti dei sacedorti per la confessione.<\/div>\n<div>\u00a0<\/div>\n<div>Alla fine della santa Messa sar\u00e0 offerto un piccolo rinfresco.<\/div>\n<div>Chi fosse interessato a cantare con il coro di CL, pu\u00f2 contattare Luca allo : 339\/263.4887\u00a0<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Arcidiocesi di Genova &#8211; Ufficio per la Pastorale universitaria Santa Messa inizio anno accademico; Chiesa N.S. della Consolazione e S. Vincenzo Martire ( Via XX Settembre) alle ore 18 Presieduta da S.E. Mons. Nicol\u00f2 Anselmi &#8211; Vescovo Ausiliare di Genova \u00a0 Sono invitati studenti, docenti, personale tecnico ed amministrativo dell&#8217;ateneo genovese. Saranno presenti dei sacedorti [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":98,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-97","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/comments?post=97"}],"version-history":[{"count":0,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/97\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media\/98"}],"wp:attachment":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media?parent=97"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/categories?post=97"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/tags?post=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}