{"id":54,"date":"2014-11-11T12:41:00","date_gmt":"2014-11-11T11:41:00","guid":{"rendered":"http:\/\/universita.chiesadigenova.it\/sabato-29-novembre-2014-ritiro-spirituale-per-docenti-universitari\/"},"modified":"2014-11-11T12:41:00","modified_gmt":"2014-11-11T11:41:00","slug":"sabato-29-novembre-2014-ritiro-spirituale-per-docenti-universitari","status":"publish","type":"post","link":"https:\/\/www.chiesadigenova.it\/universita\/sabato-29-novembre-2014-ritiro-spirituale-per-docenti-universitari\/","title":{"rendered":"Sabato 29 novembre 2014 &#8211; Ritiro Spirituale per Docenti Universitari"},"content":{"rendered":"<div>\u00a0Gentilissimi professori, ricercatori, assegnisti di ricerca, dottorandi,<\/div>\n<div>alla luce del grande apprezzamento e del buon esito dell\u0092appuntamento di maggio scorso, desideriamo in occasione dell\u0092Avvento, insieme ai sacerdoti cappellani universitari, proporVi un\u0092esperienza significativa e sostanziosa offrendoVi una mezza giornata di meditazione secondo il metodo degli Esercizi Spirituali di S. Ignazio.<\/div>\n<div><strong>Sabato 29 Novembre  h. 10-17.30 presso il Seminario Arcivescovile (Salita Cavallo, 104 al Righi).<\/strong><\/div>\n<div>Il Dio che si rivela nella Storia di Salvezza \u00e8 un Dio che \u0093Parla\u0094, si comunica (\u0093E Dio disse\u0085\u0094 Gn. 1,3) all\u0092uomo creato capace di relazione con  Dio (capax Dei). E se Dio \u0093parla\u0094 la prima, pi\u00f9 importante e utile forma di preghiera \u00e8 \u0093Ascoltare\u0094 nel silenzio la \u0093Parola\u0094 nel proprio cuore. La \u0093Parola di Dio viva ed efficace\u0094 (Eb 4,12). Per l\u0092occasione la guida sar\u00e0 un gesuita, prof.  P. Fausto Gianfeda S.J.<\/div>\n<div>\u00a0<\/div>\n<div>Durante il ritiro interverr\u00e0 S.E.R. Card. Angelo Bagnasco.<\/div>\n<div>\u00a0<\/div>\n<div>A grandi linee il programma sar\u00e0 il seguente:<\/div>\n<div>h. 10,00 Arrivo e accoglienza<\/div>\n<div>h. 10.30 spunti di meditazione e istruzione sul metodo di preghiera<\/div>\n<div>h. 11.30 silenzio e tempo personale di meditazione<\/div>\n<div>h. 13.00 incontro con S.E.R. Card. Angelo Bagnasco<\/div>\n<div>h. 13.30 pranzo e tempo libero<\/div>\n<div>h. 14.30 spunti per la meditazione del pomeriggio<\/div>\n<div>h. 16.30 condivisione<\/div>\n<div>h. 17.00 vespri e saluti<\/div>\n<div>\u00a0<\/div>\n<div>Per informazioni, potete contattare telefonicamente lo 010\/570.43.89 al mattino dalle 9 alle 13 o inviare una mail all&#8217;indirizzo: universita@diocesi.genova.it<\/div>\n<div>\u00a0<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Gentilissimi professori, ricercatori, assegnisti di ricerca, dottorandi, alla luce del grande apprezzamento e del buon esito dell\u0092appuntamento di maggio scorso, desideriamo in occasione dell\u0092Avvento, insieme ai sacerdoti cappellani universitari, proporVi un\u0092esperienza significativa e sostanziosa offrendoVi una mezza giornata di meditazione secondo il metodo degli Esercizi Spirituali di S. Ignazio. Sabato 29 Novembre h. 10-17.30 presso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-54","post","type-post","status-publish","format-standard","hentry","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/comments?post=54"}],"version-history":[{"count":0,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/54\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media?parent=54"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/categories?post=54"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/tags?post=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}