{"id":507,"date":"2025-02-26T12:13:22","date_gmt":"2025-02-26T11:13:22","guid":{"rendered":"https:\/\/www.chiesadigenova.it\/universita\/?p=507"},"modified":"2025-02-26T12:13:22","modified_gmt":"2025-02-26T11:13:22","slug":"mercoledi-5-marzo-2025-la-s-messa-con-imposizione-delle-ceneri","status":"publish","type":"post","link":"https:\/\/www.chiesadigenova.it\/universita\/mercoledi-5-marzo-2025-la-s-messa-con-imposizione-delle-ceneri\/","title":{"rendered":"Mercoled\u00ec 5 marzo 2025 la S. Messa con imposizione delle Ceneri"},"content":{"rendered":"<p><strong>Mercoled\u00ec 5 marzo 2025 alle ore 13.15<\/strong> nella Cappellina di Via Balbi 5 e nella chiesa di San Francesco d&#8217;Albaro viene celebrata la S. Messa con l&#8217;imposizione delle Ceneri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercoled\u00ec 5 marzo 2025 alle ore 13.15 nella Cappellina di Via Balbi 5 e nella chiesa di San Francesco d&#8217;Albaro viene celebrata la S. Messa con l&#8217;imposizione delle Ceneri.<\/p>\n","protected":false},"author":3,"featured_media":508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/comments?post=507"}],"version-history":[{"count":1,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/507\/revisions"}],"predecessor-version":[{"id":509,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/507\/revisions\/509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media\/508"}],"wp:attachment":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media?parent=507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/categories?post=507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/tags?post=507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}