{"id":424,"date":"2024-06-10T17:20:47","date_gmt":"2024-06-10T15:20:47","guid":{"rendered":"https:\/\/www.chiesadigenova.it\/universita\/?p=424"},"modified":"2024-06-10T17:20:47","modified_gmt":"2024-06-10T15:20:47","slug":"mercoledi-19-giugno-2024-incontro-di-cosa-e-fatta-la-speranza-il-dolore-la-solitudine-la-vita-che-resta-da-vivere","status":"publish","type":"post","link":"https:\/\/www.chiesadigenova.it\/universita\/mercoledi-19-giugno-2024-incontro-di-cosa-e-fatta-la-speranza-il-dolore-la-solitudine-la-vita-che-resta-da-vivere\/","title":{"rendered":"Mercoled\u00ec 19 giugno 2024 incontro &#8220;Di cosa \u00e8 fatta la speranza. Il dolore, la solitudine, la vita che resta da vivere&#8221;"},"content":{"rendered":"<p>Il Centro culturale Charles P\u00e9guy, insieme all\u2019Ufficio per la Pastorale Universitaria dell\u2019Arcidiocesi di Genova, a partire dalla lettura del libro di Emmanuel Exitu \u201cDi cosa \u00e8 fatta la speranza\u201d sulla vita e l\u2019opera di Cicely Saunders, offre una riflessione e un dialogo confrontandosi con gli attuali interrogativi sulle cure e sulle scelte alla fine della vita.<\/p>\n<p><strong>Mercoled\u00ec 19 giugno 2024, ore 20.45, presso la Sala Quadrivium, Piazza S. Marta 2, Genova nell\u2019incontro \u201cDi cosa \u00e8 fatta la speranza. Il dolore, la solitudine, la vita che resta da vivere\u201d il Dott. Marco MALTONI, Direttore Unit\u00e0 cure palliative AUSL Romagna e Presidente dell\u2019Associazione \u201cSul sentiero di Cicely\u201d e il Prof. Antonio D\u2019ALOIA, Ordinario di Diritto Costituzionale dell\u2019Universit\u00e0 di Parma, dialogheranno sui temi proposti dal volume che richiamano la viva attualit\u00e0 del dibattito in corso.<\/strong><\/p>\n<p>L\u2019incontro nasce da un dialogo tra giovani, medici e giuristi, alcuni dei quali coinvolti anche nel percorso Vita e Vangelo, un gruppo di riflessione promosso dall\u2019Arcivescovo padre Marco Tasca sulle tematiche del fine vita. Dinanzi a questi temi ci si pu\u00f2 trovare su diverse posizioni. \u00c8 Simone che spiega due possibili alternative: \u201cla prima consiste nell\u2019idea che la \u201clegge\u201d abbia il compito di difendere tout court ogni momento della vita, impedendo che vengano attuate condotte contrarie; l\u2019altra, invece, prende le mosse dalla consapevolezza che il diritto \u00e8 uno strumento che una comunit\u00e0 utilizza per autoregolarsi in un dato momento storico e che, quindi, pu\u00f2 mutare\u201d. Ma entrambe le posizioni possono avere qualcosa di vero? Per rispondere, ci dice Micol, \u201c\u00e8\u2019 sorto il desiderio di approfondire un tema tanto delicato che, allo stesso tempo, invita a trovare modalit\u00e0 per dialogare con chi ha comunque \u201cdiverse visioni del mondo\u201d come dice Papa Francesco, quando ricorda che \u201cin seno alle societ\u00e0 democratiche, argomenti delicati come questi vanno affrontati con pacatezza: in modo serio e riflessivo, e ben disposti a trovare soluzioni \u2013 anche normative \u2013 il pi\u00f9 possibile condivise. \u2026 \u201c per promuovere il bene comune nelle situazioni concrete\u00bb. Forse, l\u2019unica possibilit\u00e0, per tutti, potrebbe essere quella di soffermare l\u2019attenzione sulla compagnia alla persona che soffre e sulla prospettazione di una presa in carico globale che possa anche far vedere, al paziente, la possibilit\u00e0 di affrontare con speranza ci\u00f2 che gli resta da vivere. Infatti, come faceva anche notare Luigi Carlo Vinelli recentemente proprio sul <em>Il cittadino<\/em>, ci si potrebbe interrogare sugli strumenti (anche normativi) che potrebbero permettere di non lasciare nessuno solo e, di conseguenza, favorire che chi si trovi in una situazione di particolare dolore e fatica sia realmente accompagnato.<\/p>\n<p>Micol e Simone, insieme a Federica e Francesco, hanno coinvolto alcuni medici con molti anni di esperienza in questo ambito, i responsabili del Centro culturale Charles Peguy e don Tommaso Danovaro e l\u2019Ufficio di Pastorale Universitaria, per proporre insieme un incontro pubblico, un contributo offerto alla citt\u00e0 per riflettere e approfondire il tema.<\/p>\n<p>Sulla strada hanno incontrato un piccolo grande best seller \u201cDi cosa \u00e8 fatta la speranza\u201d di Emmanuel Exitu, edizioni Bompiani, che \u00e8 giunto in poco tempo alla sua quarta ristampa e ha riscosso il plauso di autori come Daniele Mencarelli e Alessandro D\u2019Avenia. In forma di romanzo Exitu racconta le vicende umane e professionali di Cecily Saunders: prima, infermiera durante la II Guerra mondiale, assiste e cerca di alleviare le sofferenze dei feriti, poi, assistente sociale, si trova a lenire il dolore dei malati che le sono affidati. E\u2019 lei\u00a0 che nel 1967 cre\u00f2 il primo hospice e avvi\u00f2 la medicina che prende in carico l\u2019intera persona. La sua fu una rivoluzione a partire dalla speranza di cura. Come scrive Alessandro D\u2019Avenia: <em>\u201cCicely fu visionaria perch\u00e9 sperava: essere visionari non significa avere visioni, ma scorgere il possibile dove tutti vedono l\u2019impossibile. Bisogna diventare visionari del qui e ora.<\/em>&#8221; Una speranza che si nutra di concretezza e di persone presenti: la controcopertina del libro ricorda che \u201c<em>la speranza \u00e8 fatta di cose che hanno bisogno di qualcuno che le faccia accadere.<\/em>\u201d A partire da qui le domande a Marco Maltoni, che ha voluto proseguire \u201cil sentiero di Cicely\u201d e Antonio D\u2019Aloia che si \u00e8 confrontato con i diritti e i livelli essenziali delle prestazioni sociali e sanitarie. Un dialogo per capire, per approfondire, per far crescere la speranza.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Centro culturale Charles P\u00e9guy, insieme all\u2019Ufficio per la Pastorale Universitaria dell\u2019Arcidiocesi di Genova, a partire dalla lettura del libro di Emmanuel Exitu \u201cDi cosa \u00e8 fatta la speranza\u201d sulla vita e l\u2019opera di Cicely Saunders, offre una riflessione e un dialogo confrontandosi con gli attuali interrogativi sulle cure e sulle scelte alla fine della [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/comments?post=424"}],"version-history":[{"count":1,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/424\/revisions"}],"predecessor-version":[{"id":426,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/424\/revisions\/426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media\/425"}],"wp:attachment":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media?parent=424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/categories?post=424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/tags?post=424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}