{"id":411,"date":"2024-02-08T12:18:38","date_gmt":"2024-02-08T11:18:38","guid":{"rendered":"https:\/\/www.chiesadigenova.it\/universita\/?p=411"},"modified":"2024-02-08T14:39:58","modified_gmt":"2024-02-08T13:39:58","slug":"mercoledi-14-febbraio-2024-giorno-delle-ceneri-le-ss-messe-in-via-balbi-e-a-s-francesco-dalbaro","status":"publish","type":"post","link":"https:\/\/www.chiesadigenova.it\/universita\/mercoledi-14-febbraio-2024-giorno-delle-ceneri-le-ss-messe-in-via-balbi-e-a-s-francesco-dalbaro\/","title":{"rendered":"Mercoled\u00ec 14 febbraio 2024, giorno delle &#8216;Ceneri&#8217;, le SS. Messe in Via Balbi e a S. Francesco d&#8217;Albaro"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\"><strong>Mercoled\u00ec 14 febbraio 2024 alle ore 13.15<\/strong>, il giorno delle &#8216;Ceneri&#8217;, in via Balbi e nella chiesa di San Francesco d&#8217;Albaro viene celebrata la S. Messa con il rito di imposizione delle Ceneri, che segna l&#8217;inizio della Quaresima.<img loading=\"lazy\" decoding=\"async\" class=\" wp-image-412 alignright\" src=\"https:\/\/www.chiesadigenova.it\/universita\/wp-content\/uploads\/sites\/18\/2024\/02\/ceneri2024-300x300.jpg\" alt=\"\" width=\"677\" height=\"677\" srcset=\"https:\/\/www.chiesadigenova.it\/universita\/wp-content\/uploads\/sites\/18\/2024\/02\/ceneri2024-300x300.jpg 300w, https:\/\/www.chiesadigenova.it\/universita\/wp-content\/uploads\/sites\/18\/2024\/02\/ceneri2024-1024x1024.jpg 1024w, https:\/\/www.chiesadigenova.it\/universita\/wp-content\/uploads\/sites\/18\/2024\/02\/ceneri2024-150x150.jpg 150w, https:\/\/www.chiesadigenova.it\/universita\/wp-content\/uploads\/sites\/18\/2024\/02\/ceneri2024-768x768.jpg 768w, https:\/\/www.chiesadigenova.it\/universita\/wp-content\/uploads\/sites\/18\/2024\/02\/ceneri2024-600x600.jpg 600w, https:\/\/www.chiesadigenova.it\/universita\/wp-content\/uploads\/sites\/18\/2024\/02\/ceneri2024-800x800.jpg 800w, https:\/\/www.chiesadigenova.it\/universita\/wp-content\/uploads\/sites\/18\/2024\/02\/ceneri2024.jpg 1072w\" sizes=\"auto, (max-width: 677px) 100vw, 677px\" \/><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mercoled\u00ec 14 febbraio 2024 alle ore 13.15, il giorno delle &#8216;Ceneri&#8217;, in via Balbi e nella chiesa di San Francesco d&#8217;Albaro viene celebrata la S. Messa con il rito di imposizione delle Ceneri, che segna l&#8217;inizio della Quaresima.<\/p>\n","protected":false},"author":3,"featured_media":413,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/comments?post=411"}],"version-history":[{"count":2,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/411\/revisions"}],"predecessor-version":[{"id":415,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/411\/revisions\/415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media\/413"}],"wp:attachment":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media?parent=411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/categories?post=411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/tags?post=411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}