{"id":358,"date":"2023-02-20T15:28:37","date_gmt":"2023-02-20T14:28:37","guid":{"rendered":"https:\/\/www.chiesadigenova.it\/universita\/?p=358"},"modified":"2023-02-24T14:55:47","modified_gmt":"2023-02-24T13:55:47","slug":"358-2","status":"publish","type":"post","link":"https:\/\/www.chiesadigenova.it\/universita\/358-2\/","title":{"rendered":"Luned\u00ec 27 febbraio 2023 la presentazione del libro su Armida Barelli"},"content":{"rendered":"<p>Il <strong>27 febbraio<\/strong> la Pastorale Universitaria in collaborazione con Azione Cattolica, MEIC e la Libreria San Paolo, viene presentato il libro su Armida Barelli fondatrice dell\u2019 Universit\u00e0 Cattolica del Sacro Cuore e beata dell\u2019AC.<\/p>\n<p>Il titolo del volume a cura di Ernesto Preziosi \u00e8 &#8220;La zingara del buon Dio <strong>ARMIDA BARELLI<\/strong> storia di una donna che ha cambiato un&#8217;epoca&#8221; con la prefazione di <strong>PAPA FRANCESCO<\/strong>.<\/p>\n<p>Con l&#8217;Autore, intervengono: Eleonora Russo, Martina Bottaro, Luca Mazzolino<br \/>\nTestimonianza di Bona Barelli<\/p>\n<p>Siamo tutti invitati presso la<strong> Sala Quadrivium<\/strong>\u00a0luned\u00ec 27 febbraio 2023 alle ore 18.<\/p>\n<p>&nbsp;<\/p>\n<p><em>In allegato il volantino da diffondere<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 27 febbraio la Pastorale Universitaria in collaborazione con Azione Cattolica, MEIC e la Libreria San Paolo, viene presentato il libro su Armida Barelli fondatrice dell\u2019 Universit\u00e0 Cattolica del Sacro Cuore e beata dell\u2019AC. Il titolo del volume a cura di Ernesto Preziosi \u00e8 &#8220;La zingara del buon Dio ARMIDA BARELLI storia di una donna [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/comments?post=358"}],"version-history":[{"count":3,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/358\/revisions"}],"predecessor-version":[{"id":363,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/358\/revisions\/363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media\/359"}],"wp:attachment":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media?parent=358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/categories?post=358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/tags?post=358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}