{"id":198,"date":"2019-09-30T12:19:00","date_gmt":"2019-09-30T10:19:00","guid":{"rendered":"http:\/\/universita.chiesadigenova.it\/lunedi-7-ottobre-2019-alle-ore-18-30-la-s-messa-di-inizio-anno-universitario\/"},"modified":"2019-09-30T12:19:00","modified_gmt":"2019-09-30T10:19:00","slug":"lunedi-7-ottobre-2019-alle-ore-18-30-la-s-messa-di-inizio-anno-universitario","status":"publish","type":"post","link":"https:\/\/www.chiesadigenova.it\/universita\/lunedi-7-ottobre-2019-alle-ore-18-30-la-s-messa-di-inizio-anno-universitario\/","title":{"rendered":"Luned\u00ec 7 ottobre 2019 alle ore 18.30 la S. messa di inizio anno universitario"},"content":{"rendered":"<div style=\"text-align: justify;\"><strong>Luned\u00ec 7 ottobre 2019 alle ore 18.30<\/strong> celebrazione della Santa Messa per l&#8217;inizio anno universitario nel Santuario di Nostra Signora delle Grazie al Molo (Piazza delle Grazie).<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">La Santa Messa sar\u00e0 celebrata da Mons. Nicol\u00f2 Anselmi, Vescovo Ausiliare della Diocesi di Genova.<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">Alle ore 18 verr\u00e0 recitato il Santo Rosario per il mese missionario voluto dal Santo Padre.<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">A seguire visita alla cripta e mini rinfresco.\u00a0<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">Sono invitati a partecipare Docenti, Personale Tecnico ed Amministrativo e Studenti.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec 7 ottobre 2019 alle ore 18.30 celebrazione della Santa Messa per l&#8217;inizio anno universitario nel Santuario di Nostra Signora delle Grazie al Molo (Piazza delle Grazie). \u00a0 La Santa Messa sar\u00e0 celebrata da Mons. Nicol\u00f2 Anselmi, Vescovo Ausiliare della Diocesi di Genova. \u00a0 Alle ore 18 verr\u00e0 recitato il Santo Rosario per il mese [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":199,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/comments?post=198"}],"version-history":[{"count":0,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/198\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media\/199"}],"wp:attachment":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media?parent=198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/categories?post=198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/tags?post=198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}