{"id":103,"date":"2017-01-16T12:16:00","date_gmt":"2017-01-16T11:16:00","guid":{"rendered":"http:\/\/universita.chiesadigenova.it\/missione-gioia-piena\/"},"modified":"2017-01-16T12:16:00","modified_gmt":"2017-01-16T11:16:00","slug":"missione-gioia-piena","status":"publish","type":"post","link":"https:\/\/www.chiesadigenova.it\/universita\/missione-gioia-piena\/","title":{"rendered":"MISSIONE GIOIA PIENA"},"content":{"rendered":"<div>\u00a0La Pastorale Giovanile, in unione con la Consulta Diocesana e con l\u0092Arcivescovo, ha deciso di dare inizio per l&#8217;anno pastorale 2016-2017 ad una attenzione particolare al mondo giovanile indicendo l&#8217;anno &#8220;<strong style=\"font-size: 11pt;\">Gioia Piena<\/strong>&#8220;.<\/div>\n<div style=\"margin: 0cm 0cm 0.0001pt; background-image: initial; background-position: initial; background-size: initial; background-repeat: initial; background-attachment: initial; background-origin: initial; background-clip: initial;\"><br > La proposta di Ges\u00f9 ai giovani \u00e8 una proposta di gioia, \u00e8 la risposta al bisogno di felicit\u00e0 che abita nel cuore di ogni ragazzo. Proprio la persona di Ges\u00f9 sar\u00e0 al centro di questo anno.<br > La frase del Vangelo\u00a0<strong>&#8220;Vi dico queste cose perch\u00e9 la mia\u00a0gioia sia in voi e la vostra\u00a0gioia sia piena\u0094,<\/strong>\u00a0riassume pienamente l&#8217;opera di Ges\u00f9 che agisce per noi, per la nostra felicit\u00e0.<br > L&#8217;anno\u00a0vorrebbe essere un modo di\u00a0<strong>rilanciare tutta la pastorale giovanile in chiave pi\u00f9 missionaria<\/strong>.\u00a0<br > Il titolo e il logo esprimono l\u0092idea che la vita cristiana con Ges\u00f9 dona gioia, felicit\u00e0 e speranza per tutti. La missione, come tutta la pastorale giovanile, ha un orizzonte vocazionale finalizzato ad aiutare i giovani a scoprire e realizzare la pienezza della propria felicit\u00e0 nella volont\u00e0 di Dio. Ges\u00f9 \u00e8 vivente nella Chiesa.\u00a0I giovani, protagonisti e destinatari di quest&#8217;anno, sono quelli\u00a0<strong>dai 14 anni fino ai 30-35enni<\/strong>, in particolare coloro che hanno gi\u00e0 ricevuto la Santa Cresima; la grazia dello Spirito Santo ricevuta durante la Confermazione sar\u00e0 la forza principale che sosterr\u00e0 tutta la missione. Le attivit\u00e0 dei giovani durante l&#8217;anno saranno fatte dagli stessi giovani per i giovani, nella semplicit\u00e0 dell&#8217;annuncio.I gruppi di Lavoro sono 12; per ognuno di esso ci sono alcune persone che coordineranno le attivit\u00e0, in particolar modo un giovane, un sacerdote e una religiosa. I gruppi sono aperti se volete unirvi!\u00a0<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0La Pastorale Giovanile, in unione con la Consulta Diocesana e con l\u0092Arcivescovo, ha deciso di dare inizio per l&#8217;anno pastorale 2016-2017 ad una attenzione particolare al mondo giovanile indicendo l&#8217;anno &#8220;Gioia Piena&#8220;. La proposta di Ges\u00f9 ai giovani \u00e8 una proposta di gioia, \u00e8 la risposta al bisogno di felicit\u00e0 che abita nel cuore di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/comments?post=103"}],"version-history":[{"count":0,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/posts\/103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media\/104"}],"wp:attachment":[{"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/media?parent=103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/categories?post=103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesadigenova.it\/universita\/wp-json\/wp\/v2\/tags?post=103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}